{"id":2501,"date":"2016-05-21T17:06:31","date_gmt":"2016-05-21T16:06:31","guid":{"rendered":"https:\/\/www.powertechsystems.eu\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/"},"modified":"2026-01-16T08:56:17","modified_gmt":"2026-01-16T07:56:17","slug":"powerrack-systeme-modulaire-de-stockage-lithium-ion","status":"publish","type":"page","link":"https:\/\/www.powertechsystems.eu\/fr\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/","title":{"rendered":"PowerRack - Syst\u00e8me \u00e9volutif de stockage d'\u00e9nergie au lithium-ion"},"content":{"rendered":"<a href=\"\/fr\/produits\/pack-batterie-12v-lithium-powerbrick\/\" class=\"button primary is-outline is-xxsmall\" style=\"border-radius:99px;\">\n\t\t<span>PowerBrick 12V<\/span>\n\t<\/a>\n\r\n<a href=\"\/fr\/produits\/pack-batterie-24v-lithium-ion-powerbrick\/\" class=\"button primary is-outline is-xxsmall\" style=\"border-radius:99px;\">\n\t\t<span>PowerBrick 24V<\/span>\n\t<\/a>\n\r\n<a href=\"\/fr\/produits\/pack-batterie-48v-lithium-ion\/\" class=\"button primary is-outline is-xxsmall\" style=\"border-radius:99px;\">\n\t\t<span>PowerBrick 48V<\/span>\n\t<\/a>\n\r\n<a href=\"\/fr\/produits\/systeme-modulaire-powermodule-48v-lithium\/\" class=\"button primary is-outline is-xxsmall\" style=\"border-radius:99px;\">\n\t\t<span>PowerModule\u00ae<\/span>\n\t<\/a>\n\r\n<a href=\"\/fr\/produits\/powerrack-systeme-modulaire-de-stockage-lithium-ion\/\" class=\"button primary is-xxsmall\" style=\"border-radius:99px;\">\n\t\t<span>PowerRack ind\u00e9pendants<\/span>\n\t<\/a>\n\r\n<a href=\"\/fr\/produits\/autres\/battery-management-system-bms\/\" class=\"button primary is-outline is-xxsmall\" style=\"border-radius:99px;\">\n\t\t<span>Autres<\/span>\n\t<\/a>\n\r\n\t<div id=\"gap-1017920380\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1017920380 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<h1>PowerRack : Syst\u00e8me \u00e9volutif de stockage d'\u00e9nergie au lithium-ion<\/h1>\n<div class=\"su-row\">\n<div class=\"su-column su-column-size-1-4\"><div class=\"su-column-inner su-u-clearfix su-u-trim\">\n<img decoding=\"async\" class=\"aligncenter size-medium wp-image-2485\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/05\/PowerRack-Cabinet-144x300.webp\" alt=\"Armoire \u00e9lectrique\" width=\"144\" height=\"300\" \/><br \/>\n<\/div><\/div>\n<div class=\"su-column su-column-size-1-2\"><div class=\"su-column-inner su-u-clearfix su-u-trim\">\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-2465\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/05\/PowerRack.webp\" alt=\"PowerRack - Syst\u00e8me \u00e9volutif de stockage d&#039;\u00e9nergie au lithium-ion\" width=\"493\" height=\"300\" \/><br \/>\n<\/div><\/div>\n<div class=\"su-column su-column-size-1-4\"><div class=\"su-column-inner su-u-clearfix su-u-trim\">\n<img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/2\/2022\/04\/MIF_V_EN-275x400.webp\" alt=\"Module PowerRack\" width=\"275\" height=\"400\" class=\"aligncenter size-medium wp-image-11736\" \/><br \/>\n<\/div><\/div>\n<\/div>\n<h5><span class=\"su-highlight\" style=\"background:#ddff99;color:#000000\">&nbsp;Le syst\u00e8me PowerRack\u00ae est d\u00e9sormais approuv\u00e9 par le Bureau Veritas Marine &amp; Offshore et est certifi\u00e9 pour les applications marines. <a href=\"\/fr\/powerrack-lithium-ion-batteries-system-now-approved-bureau-veritas-marine-offshore\/\">Lire la suite...<\/a>&nbsp;<\/span><\/h5>\n<h5><span class=\"su-highlight\" style=\"background:#ddff99;color:#000000\">&nbsp;PowerRack\u00ae \u00e9quipe \u201c<a href=\"\/fr\/ducasse-sur-seine-le-bateau-restaurant-etoile-michelin-electrique\/\">Ducasse sur Seine<\/a>\u201dLe premier bateau restaurant 100% \u00e9lectrique \u00e9toil\u00e9 Michelin, bas\u00e9 au pied de la Tour Eiffel, \u00e0 Paris, en France. <a href=\"\/fr\/ducasse-sur-seine-le-bateau-restaurant-etoile-michelin-electrique\/\">Lire la suite...<\/a>&nbsp;<\/span><\/h5>\n<p>\nLe syst\u00e8me PowerRack est un syst\u00e8me puissant et \u00e9volutif de gestion de l'information. <a href=\"\/fr\/technique\/la-technologie-lithium-fer-phosphate\/\" rel=\"noopener noreferrer\" target=\"_blank\">Lithium Fer Phosphate<\/a> Syst\u00e8me de stockage d'\u00e9nergie pour une grande vari\u00e9t\u00e9 d'applications de stockage d'\u00e9nergie (traction lourde, stationnaire, industrie, ASI, t\u00e9l\u00e9communications, r\u00e9seaux faibles et hors-r\u00e9seau, syst\u00e8mes d'autoconsommation, smart-grid, etc.)\n<\/p>\n<p>\nLes modules PowerRack sont mont\u00e9s dans une armoire 19 pouces pour un gain de place et une densit\u00e9 \u00e9nerg\u00e9tique accrue. Le format standard de l'armoire 19 pouces permet une compatibilit\u00e9 totale avec certaines applications professionnelles telles que les batteries de t\u00e9l\u00e9communication de secours, les syst\u00e8mes UPS, les sous-stations et certains syst\u00e8mes industriels.\n<\/p>\n<p>\nPowerTech Systems a rigoureusement s\u00e9lectionn\u00e9 et test\u00e9 les meilleures cellules lithium-fer-phosphate de leur cat\u00e9gorie qui sont assembl\u00e9es dans ce produit, afin de garantir une dur\u00e9e de vie et des performances \u00e9lev\u00e9es.<br \/>\nLe lithium-phosphate de fer (LFP) est actuellement la meilleure solution pour le stockage de l'\u00e9nergie, en raison de sa durabilit\u00e9, <a href=\"\/fr\/technique\/la-securite-des-batteries-lithium-ion\/\" rel=\"noopener noreferrer\" target=\"_blank\">sa grande s\u00e9curit\u00e9<\/a> et sa sup\u00e9riorit\u00e9 technique par rapport aux autres technologies disponibles sur le march\u00e9.\n<\/p>\n<h3>Exemple d'application :<\/h3>\n<div class=\"row\"  id=\"row-1616429658\">\n\n\t<div id=\"col-2102743763\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a href=\"\/fr\/ducasse-sur-seine-le-bateau-restaurant-etoile-michelin-electrique\/\" rel=\"noopener\" target=\"_blank\"><figure id=\"attachment_9092\" aria-describedby=\"caption-attachment-9092\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/2\/2019\/10\/Ducasse-sur-Seine8-300x200.webp\" alt=\"Syst\u00e8me PowerRack \u00e0 bord du &#039;Ducasse sur seine&#039;, Paris, France\" width=\"300\" height=\"200\" class=\"size-medium wp-image-9768\" \/><figcaption id=\"caption-attachment-9092\" class=\"wp-caption-text\">Syst\u00e8me PowerRack \u00e0 bord du \u2018Ducasse sur seine\u2019, Paris, France<\/figcaption><\/figure><\/a><br \/>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-655142686\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Ducasse-sur-Seine-6.webp\" data-mfp-type=\"image\" data-mobile=\"yes\">\n<figure style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Ducasse-sur-Seine-6-300x200.webp\" alt=\"Batteries PowerRack de 740kWh dans la coque du navire &#039;Ducasse sur Seine&#039;.\" width=\"300\" height=\"200\" class=\"size-medium wp-image-9766\" \/><figcaption class=\"wp-caption-text\">Batteries PowerRack de 740kWh dans la coque du navire \u201cDucasse sur Seine\u201d.<\/figcaption><\/figure><\/span>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-827666010\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a href=\"\/fr\/le-systeme-de-batteries-powerrack-a-bord-du-bateau-logistique-fludis\/\" rel=\"noopener\" target=\"_blank\"><figure id=\"attachment_9094\" aria-describedby=\"caption-attachment-9094\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/2\/2019\/10\/Fluidis2-1-300x200.webp\" alt=\"PowerRack \u00e0 bord du bateau logistique &#039;fludis&#039;, Paris, France\" width=\"300\" height=\"200\" class=\"size-medium wp-image-9770\" \/><figcaption id=\"caption-attachment-9094\" class=\"wp-caption-text\">PowerRack \u00e0 bord du bateau logistique 'fludis', Paris, France<\/figcaption><\/figure><\/a><br \/>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"su-button-center\"><a href=\"\/fr\/contact\/contact-commercial\/?your-subject=Commercial\/Technical%20inquiry%20:%20PowerRack-%20Commercial%20Inquiry%20-%20Technical%20Question#contact\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#0b5fff;border-color:#094ccc;border-radius:6px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#558fff;border-radius:6px;text-shadow:0px 0px 0px #ada8a8\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/2\/2025\/09\/sendMail.avif\" alt=\"Demande commerciale \/ Question technique\" style=\"width:21px;height:21px\" \/> Demande commerciale \/ Question technique<\/span><\/a><\/div><br\/>\n<h2>Technologie BMSMatrix\u00ae : Intelligence embarqu\u00e9e pour PowerRack<\/h2>\n<p>Le syst\u00e8me PowerRack utilise notre<a href=\"\/fr\/produits\/autres\/battery-management-system-bms\/\" rel=\"noopener noreferrer\" target=\"_blank\"> BMSMatrix Technology<\/a> pour g\u00e9rer diff\u00e9rentes combinaisons de configurations ESS. BMSMatrix\u00ae est une technologie avanc\u00e9e issue de notre recherche et d\u00e9veloppement, qui permet le d\u00e9ploiement, le contr\u00f4le et la gestion de grands syst\u00e8mes de batteries.<\/p>\n<p>BMSMatrix\u00ae est l'intelligence int\u00e9gr\u00e9e qui apporte une modularit\u00e9 et une \u00e9volutivit\u00e9 incroyables au syst\u00e8me : PowerRack peut g\u00e9rer des syst\u00e8mes d'alimentation \u00e9lectrique aussi petits que 2,5kWh-48V, mais peut facilement s'adapter \u00e0 des syst\u00e8mes d'alimentation \u00e9lectrique plus importants de plus de 1MWh-1000V.<\/p>\n<h3>Exemple d'application :<\/h3>\n<div class=\"row\"  id=\"row-174966935\">\n\n\t<div id=\"col-1664537024\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a href=\"\/fr\/batterie-lithium-ion-powerrack-de-500kwh-pour-le-marche-de-lenergie-en-allemagne\/\" rel=\"noopener\" target=\"_blank\"><figure style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/2\/2019\/10\/PowerRack-Energy-Storage-System-300x200.webp\" alt=\"PowerRack\u00ae ESS pour la r\u00e9gulation de fr\u00e9quence (configuration 820VDC\/500kWh), Borkum, Allemagne\" width=\"300\" height=\"200\" class=\"size-medium\" \/><figcaption class=\"wp-caption-text\">PowerRack\u00ae ESS pour la r\u00e9gulation de fr\u00e9quence (configuration 820VDC\/500kWh), Borkum, Allemagne<\/figcaption><\/figure><\/a><br \/>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1028125721\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/OffGrid-PowerRack-ESS.webp\" data-mfp-type=\"image\" data-mobile=\"yes\">\n   <figure id=\"attachment_9096\" aria-describedby=\"caption-attachment-9096\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/OffGrid-PowerRack-ESS-300x200.webp\" alt=\"Stockage d&#039;\u00e9nergie \u00e9olien-solaire de 500kWh en r\u00e9seau li\u00e9 \u00e0 Borkum, Allemagne\" width=\"300\" height=\"200\" class=\"size-medium wp-image-9774\" \/><figcaption id=\"caption-attachment-9096\" class=\"wp-caption-text\">Stockage d'\u00e9nergie \u00e9olien-solaire de 500kWh en r\u00e9seau li\u00e9 \u00e0 Borkum, Allemagne<\/figcaption><\/figure>\n  <\/span>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-698700980\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Self-consumption-building-75kWh-Borkum.webp\" data-mfp-type=\"image\" data-mobile=\"yes\">\n   <figure id=\"attachment_9094\" aria-describedby=\"caption-attachment-9094\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Self-consumption-building-75kWh-Borkum-300x200.webp\" alt=\"Stockage de 75 kWh pour l&#039;autoconsommation B\u00e2timent, Allemagne\" width=\"300\" height=\"200\" class=\"size-medium wp-image-9780\" \/><figcaption id=\"caption-attachment-9094\" class=\"wp-caption-text\">Stockage de 75 kWh pour l'autoconsommation B\u00e2timent, Allemagne<\/figcaption><\/figure>\n  <\/span>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"su-button-center\"><a href=\"\/fr\/contact\/contact-commercial\/?your-subject=Commercial\/Technical%20inquiry%20:%20PowerRack-%20Commercial%20Inquiry%20-%20Technical%20Question#contact\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#0b5fff;border-color:#094ccc;border-radius:6px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#558fff;border-radius:6px;text-shadow:0px 0px 0px #ada8a8\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/2\/2025\/09\/sendMail.avif\" alt=\"Demande commerciale \/ Question technique\" style=\"width:21px;height:21px\" \/> Demande commerciale \/ Question technique<\/span><\/a><\/div><br\/>\n<h2>Plate-forme de surveillance :<\/h2>\n<div class=\"row\"  id=\"row-773525482\">\n\n\t<div id=\"col-1876780376\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/03\/Monitoring-Site-in-Operation.webp\" data-mfp-type=\"image\" data-mobile=\"yes\">\n   <figure id=\"attachment_9092\" aria-describedby=\"caption-attachment-9092\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/03\/Monitoring-Site-in-Operation-300x190.webp\" alt=\"Sites de surveillance en service\" class=\"size-medium wp-image-9092\" \/><figcaption id=\"caption-attachment-9092\" class=\"wp-caption-text\">Sites de surveillance en service<\/figcaption><\/figure>\n  <\/span>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-800032881\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/03\/Monitoring-Dashboard.webp\" data-mfp-type=\"image\" data-mobile=\"yes\">\n   <figure id=\"attachment_9096\" aria-describedby=\"caption-attachment-9096\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/03\/Monitoring-Dashboard-300x205.webp\" alt=\"Tableau de bord de suivi\"  class=\"size-medium wp-image-9096\" \/><figcaption id=\"caption-attachment-9096\" class=\"wp-caption-text\">Tableau de bord de suivi<\/figcaption><\/figure>\n  <\/span>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1339839923\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/03\/Monitoring-Site-Logs.webp\" data-mfp-type=\"image\" data-mobile=\"yes\">\n   <figure id=\"attachment_9094\" aria-describedby=\"caption-attachment-9094\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/03\/Monitoring-Site-Logs-300x202.webp\" alt=\"Journal de bord du site de surveillance\"  class=\"size-medium wp-image-9094\" \/><\/a><figcaption id=\"caption-attachment-9094\" class=\"wp-caption-text\">Journal de bord du site de surveillance<\/figcaption><\/figure>\n  <\/span>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>Un service de surveillance et de t\u00e9l\u00e9m\u00e9trie est disponible pour le syst\u00e8me de batterie PowerRack\u00ae.<br \/>\nCe service permet de contr\u00f4ler en temps r\u00e9el tous les param\u00e8tres de fonctionnement de la batterie.<br \/>\nToutes les informations sont collect\u00e9es par les r\u00e9seaux WIFI, 3G\/4G ou TCP-IP.<br \/>\nLe service est bas\u00e9 sur une interface API-REST s\u00e9curis\u00e9e dans un nuage s\u00e9curis\u00e9.<\/p>\n<p>Les principales caract\u00e9ristiques du service sont les suivantes :<\/p>\n<p><strong>Configuration et surveillance \u00e0 distance<\/strong><\/p>\n<ul>\n<li>Param\u00e9trage de toutes les fonctions de la batterie et des seuils de fonctionnement (plage de temp\u00e9rature, plage de tension, plage de courant, plage de puissance, seuils d'alerte, profondeur de d\u00e9charge maximale, etc.)<\/li>\n<li>Plus de 70 param\u00e8tres accessibles<\/li>\n<li>Mise \u00e0 jour \u00e0 distance du micrologiciel<\/li>\n<li>Visualisation de toutes les donn\u00e9es de fonctionnement de la batterie<\/li>\n<li>D\u00e9tection des incidents en phase pr\u00e9coce<\/li>\n<li>Consultation des param\u00e8tres sous forme de graphiques et de tableaux<\/li>\n<li>Gestion du parc et maintenance pr\u00e9ventive<\/li>\n<\/ul>\n<p><strong>Historique des donn\u00e9es<\/strong><\/p>\n<ul>\n<li>Les donn\u00e9es sont compress\u00e9es logiciellement en 5 niveaux en fonction de leur \u00e2ge<\/li>\n<li>Les valeurs moyennes, minimales et maximales de chaque param\u00e8tre sont conserv\u00e9es ind\u00e9finiment<\/li>\n<li>Consultation des donn\u00e9es par une fonction \u201cTime-Shift\u201c<\/li>\n<\/ul>\n<p><strong>Consultation 24 heures sur 24 et 7 jours sur 7 via l'interface WEB<\/strong><\/p>\n<ul>\n<li>Les donn\u00e9es sont accessibles sur n'importe quel navigateur Internet (PC ou smartphone) disposant d'un acc\u00e8s s\u00e9curis\u00e9 \u00e0 la plateforme<\/li>\n<li>Les donn\u00e9es sont stock\u00e9es dans une base de donn\u00e9es s\u00e9curis\u00e9e et sauvegard\u00e9es quotidiennement.<\/li>\n<li>Gestion des profils d'utilisateurs et des droits d'acc\u00e8s pour la consultation des donn\u00e9es.<\/li>\n<li>Toutes les <b><u>donn\u00e9es stock\u00e9es sont crypt\u00e9es<\/u><\/b> \u00e0 l'aide d'un algorithme leader sur le march\u00e9 pour garantir une totale confidentialit\u00e9.<\/li>\n<\/ul>\n<p><strong>Gestion d\u2019alertes SMS ou Email<\/strong><\/p>\n<ul>\n<li>Une <b>alerte par SMS ou par courrier \u00e9lectronique<\/b> peut \u00eatre configur\u00e9e pour \u00eatre d\u00e9clench\u00e9e en fonction des param\u00e8tres d\u00e9finis par l'utilisateur.<\/li>\n<li>Les alertes peuvent ouvrir automatiquement un ticket d'assistance ou de maintenance sur les outils de ticketing disponibles chez le client.<\/li>\n<p>.<\/ul>\n<div class=\"su-button-center\"><a href=\"\/fr\/contact\/contact-commercial\/?your-subject=Commercial\/Technical%20inquiry%20:%20PowerRack-%20Commercial%20Inquiry%20-%20Technical%20Question#contact\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#0b5fff;border-color:#094ccc;border-radius:6px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#558fff;border-radius:6px;text-shadow:0px 0px 0px #ada8a8\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/2\/2025\/09\/sendMail.avif\" alt=\"Demande commerciale \/ Question technique\" style=\"width:21px;height:21px\" \/> Demande commerciale \/ Question technique<\/span><\/a><\/div><br\/>\n<h3>Exemple d'application :<\/h3>\n<div class=\"row\"  id=\"row-1371111874\">\n\n\t<div id=\"col-680172866\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/02\/Self-consumption-house-5kWh-Borkum.webp\" data-mfp-type=\"image\" data-mobile=\"yes\">\n   <figure id=\"attachment_9092\" aria-describedby=\"caption-attachment-9092\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/02\/Self-consumption-house-5kWh-Borkum-300x200.webp\" alt=\"5kWh de stockage PowerRack pour une maison sur l&#039;\u00eele de Borkum \" width=\"300\" height=\"200\" class=\"size-medium wp-image-8148\" \/><figcaption id=\"caption-attachment-9092\" class=\"wp-caption-text\">5kWh de stockage PowerRack pour une maison sur l'\u00eele de Borkum, Allemagne<\/figcaption><\/figure>\n  <\/span>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1490708860\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a href=\"\/fr\/pour-la-premiere-fois-le-generateur-delectricite-mobile-a-hydrogene-mobhylpower-m30-alimente-lintegralite-dun-evenement-en-suisse\/\" rel=\"noopener\" target=\"_blank\"><figure style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/MobHylpower-PowerRack-Powidian-300x200.webp\" alt=\"Powerrack reli\u00e9 \u00e0 la pile \u00e0 hydrog\u00e8ne MobHylpower, France\" width=\"300\" height=\"200\" class=\"size-medium wp-image-9772\" \/><figcaption class=\"wp-caption-text\">Powerrack reli\u00e9 \u00e0 la pile \u00e0 hydrog\u00e8ne MobHylpower, France<\/figcaption><\/figure><\/a><br \/>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-345243077\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Powidian-MobHylpower-PowerRack-Battery.webp\" data-mfp-type=\"image\" data-mobile=\"yes\">\n   <figure id=\"attachment_9094\" aria-describedby=\"caption-attachment-9094\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Powidian-MobHylpower-PowerRack-Battery-300x200.webp\" alt=\"Batterie Powerrack de 15 kWh pour pile \u00e0 hydrog\u00e8ne, France\" width=\"300\" height=\"200\" class=\"size-medium wp-image-9778\" \/><figcaption id=\"caption-attachment-9094\" class=\"wp-caption-text\">Batterie Powerrack de 15 kWh pour pile \u00e0 hydrog\u00e8ne, France<\/figcaption><\/figure>\n  <\/span>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<h2>T\u00e9l\u00e9charger les sp\u00e9cifications du PowerRack<\/h2>\n<figure id=\"attachment_2470\" aria-describedby=\"caption-attachment-2470\" style=\"width: 250px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/links.powertechsystems.eu\/EN-PowerRack-Spec\" target=\"blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"size-full wp-image-2470\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/05\/PowerRack-Front.webp\" alt=\"T\u00e9l\u00e9charger les sp\u00e9cifications du PowerModule\" width=\"250\" \/><\/a><figcaption id=\"caption-attachment-2470\" class=\"wp-caption-text\">T\u00e9l\u00e9charger les sp\u00e9cifications du PowerRack<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>PowerRack : Scalable Lithium-Ion Energy Storage System PowerRack system is a powerful and scalable Lithium Iron Phosphate Energy Storage System for a wide variety of energy storage applications (heavy traction, stationary, industry, UPS, telecommunications, weak and off-grid, self-consumption systems, smart-grid, etc.) PowerRack modules are fitted in a 19 inches cabinet for space saving and increased [&#8230;]\n","protected":false},"author":1,"featured_media":0,"parent":495,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2501","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PowerRack: The scalable Lithium-Ion Energy Storage System<\/title>\n<meta name=\"description\" content=\"PowerRack is an advanced Lithium-ion energy storage systems with easy scalability and high flexibility. From 2.5kWh to 1MWh, up to 1024VDC, for ESS, Telecom, ancillary services.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.powertechsystems.eu\/fr\/produits\/powerrack-systeme-modulaire-de-stockage-lithium-ion\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PowerRack: The scalable Lithium-Ion Energy Storage System\" \/>\n<meta property=\"og:description\" content=\"PowerRack is an advanced Lithium-ion energy storage systems with easy scalability and high flexibility. From 2.5kWh to 1MWh, up to 1024VDC, for ESS, Telecom, ancillary services.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.powertechsystems.eu\/fr\/produits\/powerrack-systeme-modulaire-de-stockage-lithium-ion\/\" \/>\n<meta property=\"og:site_name\" content=\"PowerTech Systems\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T07:56:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Ducasse-sur-Seine-6-300x200.webp\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/powerrack-scalable-lithium-ion-energy-storage-system\\\/\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/powerrack-scalable-lithium-ion-energy-storage-system\\\/\",\"name\":\"PowerRack: The scalable Lithium-Ion Energy Storage System\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/powerrack-scalable-lithium-ion-energy-storage-system\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/powerrack-scalable-lithium-ion-energy-storage-system\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Ducasse-sur-Seine-6-300x200.webp\",\"datePublished\":\"2016-05-21T16:06:31+00:00\",\"dateModified\":\"2026-01-16T07:56:17+00:00\",\"description\":\"PowerRack is an advanced Lithium-ion energy storage systems with easy scalability and high flexibility. From 2.5kWh to 1MWh, up to 1024VDC, for ESS, Telecom, ancillary services.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/powerrack-scalable-lithium-ion-energy-storage-system\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/powerrack-scalable-lithium-ion-energy-storage-system\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/powerrack-scalable-lithium-ion-energy-storage-system\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Ducasse-sur-Seine-6-300x200.webp\",\"contentUrl\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Ducasse-sur-Seine-6-300x200.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/powerrack-scalable-lithium-ion-energy-storage-system\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PowerRack &#8211; Scalable Lithium-Ion Energy Storage System\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/\",\"name\":\"PowerTech Systems\",\"description\":\"Advanced Energy Storage Systems\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.powertechsystems.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#organization\",\"name\":\"PowerTech Systems\",\"alternateName\":\"PowerTech Systems\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/09\\\/Logo-PTS.jpg\",\"contentUrl\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/09\\\/Logo-PTS.jpg\",\"width\":499,\"height\":500,\"caption\":\"PowerTech Systems\"},\"image\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/powertech-systems-sas\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PowerRack : le syst\u00e8me modulaire de stockage d'\u00e9nergie au format rack 19 pouces","description":"PowerRack est un syst\u00e8me avanc\u00e9 de stockage d'\u00e9nergie au lithium, facilement extensible et tr\u00e8s flexible. De 2,5kWh \u00e0 1MWh, jusqu'\u00e0 1024VDC, pour ESS, Telecom, UPS...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.powertechsystems.eu\/fr\/produits\/powerrack-systeme-modulaire-de-stockage-lithium-ion\/","og_locale":"fr_FR","og_type":"article","og_title":"PowerRack: The scalable Lithium-Ion Energy Storage System","og_description":"PowerRack is an advanced Lithium-ion energy storage systems with easy scalability and high flexibility. From 2.5kWh to 1MWh, up to 1024VDC, for ESS, Telecom, ancillary services.","og_url":"https:\/\/www.powertechsystems.eu\/fr\/produits\/powerrack-systeme-modulaire-de-stockage-lithium-ion\/","og_site_name":"PowerTech Systems","article_modified_time":"2026-01-16T07:56:17+00:00","og_image":[{"url":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Ducasse-sur-Seine-6-300x200.webp","type":"","width":"","height":""}],"twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.powertechsystems.eu\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/","url":"https:\/\/www.powertechsystems.eu\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/","name":"PowerRack : le syst\u00e8me modulaire de stockage d'\u00e9nergie au format rack 19 pouces","isPartOf":{"@id":"https:\/\/www.powertechsystems.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.powertechsystems.eu\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/#primaryimage"},"image":{"@id":"https:\/\/www.powertechsystems.eu\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/#primaryimage"},"thumbnailUrl":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Ducasse-sur-Seine-6-300x200.webp","datePublished":"2016-05-21T16:06:31+00:00","dateModified":"2026-01-16T07:56:17+00:00","description":"PowerRack est un syst\u00e8me avanc\u00e9 de stockage d'\u00e9nergie au lithium, facilement extensible et tr\u00e8s flexible. De 2,5kWh \u00e0 1MWh, jusqu'\u00e0 1024VDC, pour ESS, Telecom, UPS...","breadcrumb":{"@id":"https:\/\/www.powertechsystems.eu\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.powertechsystems.eu\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.powertechsystems.eu\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/#primaryimage","url":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Ducasse-sur-Seine-6-300x200.webp","contentUrl":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2019\/10\/Ducasse-sur-Seine-6-300x200.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.powertechsystems.eu\/products\/powerrack-scalable-lithium-ion-energy-storage-system\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Products","item":"https:\/\/www.powertechsystems.eu\/products\/"},{"@type":"ListItem","position":2,"name":"PowerRack &#8211; Scalable Lithium-Ion Energy Storage System"}]},{"@type":"WebSite","@id":"https:\/\/www.powertechsystems.eu\/#website","url":"https:\/\/www.powertechsystems.eu\/","name":"PowerTech Systems","description":"Syst\u00e8mes avanc\u00e9s de stockage de l'\u00e9nergie","publisher":{"@id":"https:\/\/www.powertechsystems.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.powertechsystems.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.powertechsystems.eu\/#organization","name":"PowerTech Systems","alternateName":"PowerTech Systems","url":"https:\/\/www.powertechsystems.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.powertechsystems.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2016\/09\/Logo-PTS.jpg","contentUrl":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2016\/09\/Logo-PTS.jpg","width":499,"height":500,"caption":"PowerTech Systems"},"image":{"@id":"https:\/\/www.powertechsystems.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/powertech-systems-sas\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/pages\/2501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/comments?post=2501"}],"version-history":[{"count":0,"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/pages\/2501\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/pages\/495"}],"wp:attachment":[{"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/media?parent=2501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}