{"id":8570,"date":"2019-02-27T14:52:11","date_gmt":"2019-02-27T13:52:11","guid":{"rendered":"https:\/\/www.powertechsystems.eu\/products\/others\/soc-measurement-coulomb-counters\/"},"modified":"2026-01-16T13:16:44","modified_gmt":"2026-01-16T12:16:44","slug":"mesure-de-soc-compteurs-de-coulomb","status":"publish","type":"page","link":"https:\/\/www.powertechsystems.eu\/fr\/products\/others\/soc-measurement-coulomb-counters\/","title":{"rendered":"Mesure SoC et compteurs de coulomb"},"content":{"rendered":"<div class=\"nav-wrapper\"><ul class=\"nav nav-uppercase nav-horizontal nav-size-small nav-pills text-center nav-center\"><li class=\"\"><a href=\"https:\/\/www.powertechsystems.eu\/fr\/products\/others\/battery-management-system-bms\/\">Syst\u00e8me de gestion de la batterie (BMS)<\/a><\/li><li class=\"active\"><a href=\"https:\/\/www.powertechsystems.eu\/fr\/products\/others\/soc-measurement-coulomb-counters\/\">Mesure SoC et compteurs de coulomb<\/a><\/li><li class=\"\"><a href=\"https:\/\/www.powertechsystems.eu\/fr\/products\/others\/custom-lithium-ion-batteries\/\">Batteries lithium-ion Sur Mesure<\/a><\/li><\/ul><\/div>\n\t<div id=\"gap-660615845\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-660615845 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n<h1>Mesure SoC et compteurs de coulomb<\/h1>\n<p>PowerTech Systems propose deux types de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Coulombmeter\" rel=\"noopener\" target=\"_blank\">m\u00e8tres coulomb<\/a> : <\/p>\n<p>- le \u201c<strong>Soc-Monitor<\/strong>\u201dProduit communiquant via RS232 ou CAN Bus<\/p>\n<p>- le \u201c<strong>Compteur de Coulomb<\/strong>\u201dCe produit mesure l'\u00e9tat de charge d'une batterie et l'affiche sur un \u00e9cran int\u00e9gr\u00e9. Ce produit ne communique pas avec l'ext\u00e9rieur.<\/p>\n<p><a href=\"\/fr\/technique\/mesurer-letat-de-charge-soc-dune-batterie-lithium-ion\/\" rel=\"noopener\" target=\"_blank\">Les deux produits sont bas\u00e9s sur la m\u00e9thode d'int\u00e9gration du courant en temps r\u00e9el d\u00e9crite ici.<\/a><\/p>\n<div class=\"su-divider su-divider-style-dotted\" style=\"margin:25px 0;border-width:2px;border-color:#999999\"><\/div>\n<h2><strong>\u201cSOC-MONITOR\u201d<\/strong> : Compteur de Coulomb de haute pr\u00e9cision pour les applications industrielles et embarqu\u00e9es<\/h2>\n<div style=\"content:'', display:table; clear:both;\">\n<div style=\"text-align: center;float: left; width: 70%; padding: 25px;\">\n    <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor1.png\" data-mfp-type=\"image\" data-mobile=\"yes\">\n\t<picture><source srcset=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor1.png\" type=\"image\/png\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor1.png\" alt=\"SOCMoniteur\" width=\"100%\" class=\"myimg aligncenter\" \/>\n\t<\/picture>\n    <\/span>\n  <\/div>\n<div style=\"text-align: center;float: left; width: 30%; padding: 25px;\">\n    <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor3.png\" data-mfp-type=\"image\" data-mobile=\"yes\">\n\t<picture><source srcset=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor3.png\" type=\"image\/png\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor3.png\" alt=\"SOCMoniteur\" width=\"80%\" class=\"myimg aligncenter\" \/>\n\t<\/picture>\n    <\/span>\n    <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor4.png\" data-mfp-type=\"image\" data-mobile=\"yes\">\n\t<picture><source srcset=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor4.png\" type=\"image\/png\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor4.png\" alt=\"SOCMoniteur\" width=\"80%\" class=\"myimg aligncenter\" \/>\n\t<\/picture>\n    <\/span>\n    <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor5.png\" data-mfp-type=\"image\" data-mobile=\"yes\">\n\t<picture><source srcset=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor5.png\" type=\"image\/png\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor5.png\" alt=\"SOCMoniteur\" width=\"80%\" class=\"myimg aligncenter\" \/>\n\t<\/picture>\n    <\/span>\n  <\/div>\n<\/div>\n<div class=\"su-divider su-divider-style-\" style=\"margin:10px 0;border-width:1px;border-color:#999999\"><\/div>\n<p>Le produit \u201cSOC-monitor\u201d est un syst\u00e8me de comptage de coulomb pour tous les types de batteries au lithium avec des tensions allant jusqu'\u00e0 60VDC. Ce produit permet de communiquer les donn\u00e9es de la batterie par voie filaire (bus CAN isol\u00e9 ou RS232). <\/p>\n<p>Il int\u00e8gre un shunt de pr\u00e9cision (0,2 m\u03a9) qui offre une meilleure pr\u00e9cision que les capteurs \u00e0 effet Hall. Ce dispositif peut \u00eatre utilis\u00e9 pour mesurer la tension et le courant avec une grande pr\u00e9cision et pour <a href=\"\/fr\/technique\/mesurer-letat-de-charge-soc-dune-batterie-lithium-ion\/\" rel=\"noopener\" target=\"_blank\">estimer le SOC (\u00e9tat de charge) d'une batterie avec une grande pr\u00e9cision<\/a>.<\/p>\n<p>Toutes les informations (tension du pack, courant, SOC) peuvent \u00eatre envoy\u00e9es \u00e0 un contr\u00f4leur externe via deux protocoles de communication (bus CAN isol\u00e9 2,5KV ou RS232). Des param\u00e8tres tels que la capacit\u00e9 nominale de la batterie peuvent \u00eatre d\u00e9finis en envoyant une simple commande \u00e0 l'appareil.<\/p>\n<p>\u201cLe \u201dSOC-Monitor\" a une consommation r\u00e9siduelle tr\u00e8s faible en fonctionnement : 5,6 mA sans communication.<\/p>\n<p>Le produit comprend une r\u00e9sistance de shunt de pr\u00e9cision sur le circuit imprim\u00e9 pour des courants allant jusqu'\u00e0 100A. Pour des courants plus \u00e9lev\u00e9s, un shunt de puissance externe peut \u00eatre connect\u00e9 pour mesurer jusqu'\u00e0 plusieurs centaines d'amp\u00e8res.<\/p>\n<p>Le produit est livr\u00e9 avec un \u00e9tui de protection en plastique pour faciliter la mise en service.\n<\/p>\n<div class=\"su-tabs su-tabs-style-modern-light su-tabs-mobile-stack\" data-active=\"1\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-tabs-nav\"><span class=\"\" data-url=\"\" data-target=\"blank\" tabindex=\"0\" role=\"button\">Points cl\u00e9s<\/span><\/div><div class=\"su-tabs-panes\"><div class=\"su-tabs-pane su-u-clearfix su-u-trim\" data-title=\"Key Points\">\n<div class=\"su-list\" style=\"margin-left:0px\">\n<ul>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Type de batterie : Lithium-Ion (tous types y compris LFP) jusqu'\u00e0 60VDC (12V-24V-36V-48V nominal)<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Consommation : 5,6 mA (sans communication)<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Plage de mesure du courant : 0 - 100A avec shunt int\u00e9gr\u00e9, &gt; 100A avec shunt externe<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> R\u00e9solution de la mesure de tension : 20mV<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> R\u00e9solution de la mesure du courant : 10mA pour le courant &lt; 10A, 100mA pour les courants plus \u00e9lev\u00e9s<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> \u201cDur\u00e9e restante\u201d : 0 minute - 255 heures 59 minutes<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> P\u00e9riode d'envoi des messages : 1 seconde par d\u00e9faut. Peut \u00eatre modifi\u00e9<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> P\u00e9riode de calcul du SOC : Toutes les 100 ms<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Connecteurs d'alimentation : goujons M6 soud\u00e9s \u00e0 la carte<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Connecteur d'alimentation : bornier 2 p\u00f4les sans vis<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Port RS232 : bornier sans vis \u00e0 3 p\u00f4les<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Port CAN isol\u00e9 2,5KV : bornier sans vis \u00e0 3 p\u00f4les<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Entr\u00e9e thermistance : bornier 2 p\u00f4les sans vis<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Entr\u00e9e shunt externe : bornier 2 p\u00f4les sans vis<\/li>\n<li><i class=\"sui sui-toggle-right\" style=\"color:#4aa44a\"><\/i> Dimension du circuit imprim\u00e9 : 56 mm x 113 mm<\/li>\n<\/ul>\n<\/div>\n<\/div><\/div><\/div>\n<div class=\"su-button-center\"><a href=\"\/fr\/contact\/contact-commercial\/?your-subject=Commercial\/Technical%20inquiry%20:%20SOC%20Monitor%20-%20Commercial%20Inquiry%20-%20Technical%20Question#contact\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#0b5fff;border-color:#094ccc;border-radius:6px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#558fff;border-radius:6px;text-shadow:0px 0px 0px #ada8a8\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/2\/2025\/09\/sendMail.avif\" alt=\"Demande commerciale \/ Question technique\" style=\"width:21px;height:21px\" \/> Demande commerciale \/ Question technique<\/span><\/a><\/div><br\/>\n<div class=\"su-divider su-divider-style-dotted\" style=\"margin:25px 0;border-width:2px;border-color:#999999\"><\/div>\n<h2><strong>\u201cCOMPTEUR DE COULOMB\u201d<\/strong> : Compteur de Coulomb de haute pr\u00e9cision avec affichage<\/h2>\n<div style=\"content:'', display:table; clear:both;\">\n<div style=\"text-align: center;float: left; width: 70%; padding: 25px;\">\n<p>    <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-1.png\" data-mfp-type=\"image\" data-mobile=\"yes\">\n\t<picture><source srcset=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-1.png\" type=\"image\/png\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-1.png\" alt=\"Compteur de Coulomb avec affichage\" width=\"100%\" class=\"myimg aligncenter\" \/>\n\t<\/picture>\n    <\/span>\n  <\/div>\n<div style=\"text-align: center;float: left; width: 30%; padding: 25px;\">\n<p>    <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-2.png\" data-mfp-type=\"image\" data-mobile=\"yes\">\n\t<picture><source srcset=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-2.png\" type=\"image\/png\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-2.png\" alt=\"SOCMoniteur\" width=\"80%\" class=\"myimg aligncenter\" \/>\n\t<\/picture>\n    <\/span>\n    <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-3.png\" data-mfp-type=\"image\" data-mobile=\"yes\">\n\t<picture><source srcset=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-3.png\" type=\"image\/png\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-3.png\" alt=\"SOCMoniteur\" width=\"80%\" class=\"myimg aligncenter\" \/>\n\t<\/picture>\n    <\/span>\n    <span class=\"su-lightbox\" data-mfp-src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-4.png\" data-mfp-type=\"image\" data-mobile=\"yes\">\n\t<picture><source srcset=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-4.png\" type=\"image\/png\"><img decoding=\"async\" src=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/Coulomb-Counter-4.png\" alt=\"SOCMoniteur\" width=\"80%\" class=\"myimg aligncenter\" \/>\n\t<\/picture>\n    <\/span>\n  <\/div>\n<\/div>\n<div class=\"su-divider su-divider-style-\" style=\"margin:10px 0;border-width:1px;border-color:#999999\"><\/div>\n<p>\nLe CC 75\/150\/500 est un compteur coulombien de haute pr\u00e9cision permettant de contr\u00f4ler la tension (V), la capacit\u00e9 (Ah), la puissance (W) et l'\u00e9nergie d'une batterie. Ces informations permettent \u00e0 l'utilisateur d'obtenir un \u00e9tat de charge pr\u00e9cis en % (SoC) et la profondeur de d\u00e9charge (DoD) de la batterie. Il calcule \u00e9galement en temps r\u00e9el le temps restant avant que la batterie ne soit compl\u00e8tement vide.<\/p>\n<p>Le dispositif de comptage de Coulomb est dot\u00e9 d'une fonction m\u00e9moire qui permet de sauvegarder les informations relatives au SoC lorsque le dispositif est mis hors tension ou accidentellement d\u00e9connect\u00e9.<\/p>\n<p>Les CC 75\/150\/500 conviennent aux batteries lithium fer phosphate (LiFePO4), lithium ion et Li-Polym\u00e8re, plomb acide et nickel m\u00e9tal hybride avec une tension de travail de 8V \u00e0 80V DC.<\/p>\n<p>Ce dispositif existe en 3 versions :<br \/>\nCC75, mesure de 0 \u00e0 75A, compatible avec les bornes M6<br \/>\nCC150, mesure de 0 \u00e0 150A, compatible avec les bornes M8<br \/>\nCC500, mesure de 0 \u00e0 500A, compatible avec les bornes M10<br \/>\n<br \/>\n<a href=\"\/fr\/un-compteur-de-coulombs-haute-precision-pour-superviser-les-batteries\/\" target=\"_blank\">Plus de d\u00e9tails ici<\/a>\n<\/p>\n<div class=\"su-tabs su-tabs-style-modern-light su-tabs-mobile-stack\" data-active=\"1\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-tabs-nav\"><span class=\"\" data-url=\"\" data-target=\"blank\" tabindex=\"0\" role=\"button\">Points cl\u00e9s<\/span><\/div><div class=\"su-tabs-panes\"><div class=\"su-tabs-pane su-u-clearfix su-u-trim\" data-title=\"Key Points\">\n<div class=\"su-table su-table-alternate\">\n<table width=\"100%\">\n<tbody>\n<tr>\n<td width=\"40%\"><\/td>\n<td width=\"33%\">\u00a0<strong>Min<\/strong><\/td>\n<td width=\"33%\">\u00a0<strong>Nominal<\/strong><\/td>\n<td width=\"33%\">\u00a0<strong>Max<\/strong><\/td>\n<td width=\"33%\">\u00a0<strong>Unit\u00e9<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Tension de fonctionnement<\/td>\n<td>8.0<\/td>\n<td>50.0<\/td>\n<td>80.0<\/td>\n<td>V<\/td>\n<\/tr>\n<tr>\n<td>Consommation (r\u00e9tro\u00e9clairage allum\u00e9)<\/td>\n<td><\/td>\n<td>6.0<\/td>\n<td><\/td>\n<td>mA<\/td>\n<\/tr>\n<tr>\n<td>Consommation en veille (r\u00e9tro\u00e9clairage \u00e9teint)<\/td>\n<td><\/td>\n<td>0.7<\/td>\n<td><\/td>\n<td>mA<\/td>\n<\/tr>\n<tr>\n<td>Pr\u00e9cision de la tension<\/td>\n<td><\/td>\n<td>+\/- 1.0<\/td>\n<td><\/td>\n<td>%<\/td>\n<\/tr>\n<tr>\n<td><strong>Pr\u00e9cision actuelle<\/strong><\/td>\n<td><\/td>\n<td>+\/- 1.0<\/td>\n<td><\/td>\n<td>%<\/td>\n<\/tr>\n<tr>\n<td>Pr\u00e9cision de la capacit\u00e9<\/td>\n<td><\/td>\n<td>+\/- 1.0<\/td>\n<td><\/td>\n<td>%<\/td>\n<\/tr>\n<tr>\n<td>Valeur de la capacit\u00e9 pr\u00e9r\u00e9gl\u00e9e<\/td>\n<td>0.1<\/td>\n<td><\/td>\n<td>999.9<\/td>\n<td>Ah<\/td>\n<\/tr>\n<tr>\n<td><strong>Plage de mesure CC75<\/strong><\/td>\n<td><strong>0.0<\/strong><\/td>\n<td><strong>50.0<\/strong><\/td>\n<td><strong>75.0<\/strong><\/td>\n<td>A<\/td>\n<\/tr>\n<tr>\n<td><strong>Gamme de mesure CC150<\/strong><\/td>\n<td><strong>0.0<\/strong><\/td>\n<td><strong>100.0<\/strong><\/td>\n<td><strong>150.0<\/strong><\/td>\n<td>A<\/td>\n<\/tr>\n<tr>\n<td><strong>Plage de mesure du CC500<\/strong><\/td>\n<td><strong>0.0<\/strong><\/td>\n<td><strong>350.0<\/strong><\/td>\n<td><strong>500.0<\/strong><\/td>\n<td>A<\/td>\n<\/tr>\n<tr>\n<td>Plage de temp\u00e9rature d'affichage<\/td>\n<td>-10<\/td>\n<td>25<\/td>\n<td>50<\/td>\n<td>\u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Poids de l'affichage<\/td>\n<td><\/td>\n<td>20<\/td>\n<td><\/td>\n<td>g<\/td>\n<\/tr>\n<tr>\n<td>Dimensions de l'\u00e9cran<\/td>\n<td><\/td>\n<td>66 x 40 x 13<\/td>\n<td><\/td>\n<td>mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div><\/div><\/div>\n<div class=\"su-button-center\"><a href=\"\/fr\/contact\/contact-commercial\/?your-subject=Commercial\/Technical%20inquiry%20:%20Coulomb%20Counter%20-%20Commercial%20Inquiry%20-%20Technical%20Question#contact\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#0b5fff;border-color:#094ccc;border-radius:6px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#558fff;border-radius:6px;text-shadow:0px 0px 0px #ada8a8\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/2\/2025\/09\/sendMail.avif\" alt=\"Demande commerciale \/ Question technique\" style=\"width:21px;height:21px\" \/> Demande commerciale \/ Question technique<\/span><\/a><\/div><br\/>\n<div class=\"su-divider su-divider-style-dotted\" style=\"margin:40px 0;border-width:2px;border-color:#999999\"><\/div>\n<div class=\"sue-panel\" data-url=\"\" data-target=\"self\" style=\"background-color:#ffffff;color:#656363;border-radius:5px;-moz-border-radius:5px;-webkit-border-radius:5px;box-shadow:0px 0px 25px #e9e8e8;-moz-box-shadow:0px 0px 25px #e9e8e8;-webkit-box-shadow:0px 0px 25px #e9e8e8;border:1px solid #cccccc\"><div class=\"sue-panel-content sue-content-wrap\" style=\"padding:1px;text-align:center\"><span style=\"font-size:11px;font-weight: bold;\">Cette page et son contenu sont la propri\u00e9t\u00e9 exclusive de PowerTech Systems. Reproduction interdite sans autorisation.<\/span><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>SoC Measurement &#038; Coulomb Counters PowerTech Systems offers two types of coulomb meters : &#8211; the \u201cSoc-Monitor\u201d: product communicating via RS232 or CAN Bus &#8211; the \u201cCoulomb-Counter\u201d: this product measures the SOC of a battery and displays it on an integrated display. This product does not communicate externally. Both products are based on the real-time [&#8230;]\n","protected":false},"author":1,"featured_media":12499,"parent":8359,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8570","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Battery SoC Measurement &amp; Coulomb Counter<\/title>\n<meta name=\"description\" content=\"SoC Measurement &amp; Coulomb Counters - battery SoC Measurement &amp; Coulomb Counters for industrial and embedded applications\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Battery SoC Measurement &amp; Coulomb Counter\" \/>\n<meta property=\"og:description\" content=\"SoC Measurement &amp; Coulomb Counters - battery SoC Measurement &amp; Coulomb Counters for industrial and embedded applications\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/\" \/>\n<meta property=\"og:site_name\" content=\"PowerTech Systems\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T12:16:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/fr\\\/produits\\\/autres\\\/mesure-de-soc-compteurs-de-coulomb\\\/\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/fr\\\/produits\\\/autres\\\/mesure-de-soc-compteurs-de-coulomb\\\/\",\"name\":\"Battery SoC Measurement & Coulomb Counter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/fr\\\/produits\\\/autres\\\/mesure-de-soc-compteurs-de-coulomb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/fr\\\/produits\\\/autres\\\/mesure-de-soc-compteurs-de-coulomb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/socmonitor1.png\",\"datePublished\":\"2019-02-27T13:52:11+00:00\",\"dateModified\":\"2026-01-16T12:16:44+00:00\",\"description\":\"SoC Measurement & Coulomb Counters - battery SoC Measurement & Coulomb Counters for industrial and embedded applications\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/fr\\\/produits\\\/autres\\\/mesure-de-soc-compteurs-de-coulomb\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.powertechsystems.eu\\\/fr\\\/produits\\\/autres\\\/mesure-de-soc-compteurs-de-coulomb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/fr\\\/produits\\\/autres\\\/mesure-de-soc-compteurs-de-coulomb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/socmonitor1.png\",\"contentUrl\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/socmonitor1.png\",\"width\":800,\"height\":600,\"caption\":\"Coulombmeter by PowerTech\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/fr\\\/produits\\\/autres\\\/mesure-de-soc-compteurs-de-coulomb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/www.powertechsystems.eu\\\/products\\\/others\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SoC Measurement &#038; Coulomb Counters\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/\",\"name\":\"PowerTech Systems\",\"description\":\"Advanced Energy Storage Systems\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.powertechsystems.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#organization\",\"name\":\"PowerTech Systems\",\"alternateName\":\"PowerTech Systems\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/09\\\/Logo-PTS.jpg\",\"contentUrl\":\"https:\\\/\\\/www.powertechsystems.eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/09\\\/Logo-PTS.jpg\",\"width\":499,\"height\":500,\"caption\":\"PowerTech Systems\"},\"image\":{\"@id\":\"https:\\\/\\\/www.powertechsystems.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/powertech-systems-sas\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesure et compteur de coulomb du SoC de la batterie","description":"Mesure SoC et compteurs de Coulomb - batterie Mesure SoC et compteurs de Coulomb pour applications industrielles et embarqu\u00e9es","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/","og_locale":"fr_FR","og_type":"article","og_title":"Battery SoC Measurement & Coulomb Counter","og_description":"SoC Measurement & Coulomb Counters - battery SoC Measurement & Coulomb Counters for industrial and embedded applications","og_url":"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/","og_site_name":"PowerTech Systems","article_modified_time":"2026-01-16T12:16:44+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor1.png","type":"image\/png"}],"twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/","url":"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/","name":"Mesure et compteur de coulomb du SoC de la batterie","isPartOf":{"@id":"https:\/\/www.powertechsystems.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/#primaryimage"},"image":{"@id":"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor1.png","datePublished":"2019-02-27T13:52:11+00:00","dateModified":"2026-01-16T12:16:44+00:00","description":"Mesure SoC et compteurs de Coulomb - batterie Mesure SoC et compteurs de Coulomb pour applications industrielles et embarqu\u00e9es","breadcrumb":{"@id":"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/#primaryimage","url":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor1.png","contentUrl":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2024\/08\/socmonitor1.png","width":800,"height":600,"caption":"Coulombmeter by PowerTech"},{"@type":"BreadcrumbList","@id":"https:\/\/www.powertechsystems.eu\/fr\/produits\/autres\/mesure-de-soc-compteurs-de-coulomb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Products","item":"https:\/\/www.powertechsystems.eu\/products\/"},{"@type":"ListItem","position":2,"name":"Others","item":"https:\/\/www.powertechsystems.eu\/products\/others\/"},{"@type":"ListItem","position":3,"name":"SoC Measurement &#038; Coulomb Counters"}]},{"@type":"WebSite","@id":"https:\/\/www.powertechsystems.eu\/#website","url":"https:\/\/www.powertechsystems.eu\/","name":"PowerTech Systems","description":"Syst\u00e8mes avanc\u00e9s de stockage de l'\u00e9nergie","publisher":{"@id":"https:\/\/www.powertechsystems.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.powertechsystems.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.powertechsystems.eu\/#organization","name":"PowerTech Systems","alternateName":"PowerTech Systems","url":"https:\/\/www.powertechsystems.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.powertechsystems.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2016\/09\/Logo-PTS.jpg","contentUrl":"https:\/\/www.powertechsystems.eu\/wp-content\/uploads\/sites\/2\/2016\/09\/Logo-PTS.jpg","width":499,"height":500,"caption":"PowerTech Systems"},"image":{"@id":"https:\/\/www.powertechsystems.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/powertech-systems-sas\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/pages\/8570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/comments?post=8570"}],"version-history":[{"count":0,"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/pages\/8570\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/pages\/8359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/media\/12499"}],"wp:attachment":[{"href":"https:\/\/www.powertechsystems.eu\/fr\/wp-json\/wp\/v2\/media?parent=8570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}